{"id":23941,"date":"2024-10-01T15:51:46","date_gmt":"2024-10-01T13:51:46","guid":{"rendered":"https:\/\/www.ern.org\/?p=20124"},"modified":"2026-04-16T14:02:48","modified_gmt":"2026-04-16T12:02:48","slug":"travaux-en-cours-sur-le-bassin-de-la-dordogne-departement-du-cantal","status":"publish","type":"post","link":"https:\/\/www.ern.org\/fr\/travaux-en-cours-sur-le-bassin-de-la-dordogne-departement-du-cantal\/","title":{"rendered":"Travaux en cours sur le bassin de la Dordogne : suppression du seuil de Pont de Rhodes"},"content":{"rendered":"<section  class='av_textblock_section av-m5zgb7yy-7f53ffa08f6f990997aad52e11870c37 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Entre les d\u00e9partements du Lot et du Cantal, des travaux sont r\u00e9alis\u00e9s sur le Ressegue, affluent de la C\u00e8re. Sous la ma\u00eetrise d&rsquo;ouvrage du Syndicat Mixte de la Dordogne Moyenne et C\u00e8re Aval (SMDMCA), un obstacle \u00e0 la continuit\u00e9 de la rivi\u00e8re est en cours d&rsquo;effacement. Cette action prioritaire a \u00e9t\u00e9 jug\u00e9e importante par l&rsquo;\u00e9quipe d&rsquo;experts du plan d&rsquo;action national Auvergne-Rh\u00f4ne-Alpes sur la moule perli\u00e8re, car elle entra\u00eenerait des b\u00e9n\u00e9fices \u00e9cologiques significatifs pour la rivi\u00e8re et la connexion possible de deux populations de moules perli\u00e8res. Plus de 13 km de rivi\u00e8re en amont et 29 km de rivi\u00e8re sur l&rsquo;ensemble du bassin versant seront reconnect\u00e9s. Le site sera restaur\u00e9 au d\u00e9but du mois d&rsquo;octobre. D&rsquo;autres projets du SMDMCA sont \u00e9galement soutenus par le R\u00e9seau europ\u00e9en des rivi\u00e8res et le programme Open Rivers, notamment dans le bassin des Branugues, o\u00f9 une \u00e9tude visant \u00e0 supprimer le seuil de Batitan vient de s&rsquo;achever. (photo \u00a9 SMDMCA et Drone ki peut)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/ern-sosloirevivante.org\/wp-content\/uploads\/2024\/04\/Pontrhodes_SMDMCA-scaled.jpg\" width=\"335\" height=\"251\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/ern-sosloirevivante.org\/wp-content\/uploads\/2024\/10\/02_DESTRUCTION_SEUIL.jpg\" width=\"443\" height=\"249\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/ern-sosloirevivante.org\/wp-content\/uploads\/2024\/10\/03_APRES_TRAVAUX.jpg\" width=\"781\" height=\"439\" \/><\/p>\n<p>Plus d\u2019infos\u00a0: <a href=\"https:\/\/www.ern.org\/fr\/openrivers\/#toggle-id-2\">https:\/\/www.ern.org\/fr\/openrivers\/#toggle-id-2<\/a>\u00a0Et <a href=\"https:\/\/www.smdmca.fr\/\">https:\/\/www.smdmca.fr\/<\/a><\/p>\n<\/div><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":20140,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,19,30,36],"tags":[140,212,224],"class_list":["post-23941","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-accueil-fr","category-effacer","category-open-rivers","category-restaurer","tag-effacement-de-seuil-fr","tag-open-rivers-programme-fr","tag-pont-de-rhodes-fr"],"_links":{"self":[{"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/posts\/23941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/comments?post=23941"}],"version-history":[{"count":0,"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/posts\/23941\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/media\/20140"}],"wp:attachment":[{"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/media?parent=23941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/categories?post=23941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/tags?post=23941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}