{"id":23895,"date":"2023-06-13T18:16:27","date_gmt":"2023-06-13T16:16:27","guid":{"rendered":"https:\/\/www.ern.org\/?p=18262"},"modified":"2026-03-03T07:48:46","modified_gmt":"2026-03-03T07:48:46","slug":"sauvez-la-loi-sur-la-restauration-de-la-nature","status":"publish","type":"post","link":"https:\/\/www.ern.org\/fr\/sauvez-la-loi-sur-la-restauration-de-la-nature\/","title":{"rendered":"Sauvez la \u00ab\u00a0Loi sur la Restauration de la Nature\u00a0\u00bb"},"content":{"rendered":"<p>La Loi sur la restauration de la Nature qui sera prochainement vot\u00e9e par les parlementaires europ\u00e9ens, fixe l&rsquo;objectif de restaurer au moins 25 000 km de cours d&rsquo;eau \u00e0 \u00e9coulement libre d&rsquo;ici \u00e0 2030 (article 7) afin d&rsquo;am\u00e9liorer la connectivit\u00e9 naturelle longitudinale et lat\u00e9rale des cours d&rsquo;eau. Ces objectifs compl\u00e8tent les obligations de la directive-cadre sur l&rsquo;eau et est n\u00e9cessaire compte tenu de l&rsquo;importante d\u00e9gradation des \u00e9cosyst\u00e8mes aquatiques.<\/p>\n<p>Lire notre argumentaire mis \u00e0 disposition des Parlementaires europ\u00e9ens (<a href=\"https:\/\/www.ern.org\/wp-content\/uploads\/2023\/06\/Note_NRLartc.7_ERN_FR.pdf\">fran\u00e7ais<\/a> et en <a href=\"https:\/\/www.ern.org\/wp-content\/uploads\/2023\/06\/Note_NRLartc.7_ERN_EN.pdf\">anglais)<\/a>.<\/p>\n<p>Il faudrait m\u00eame aller plus loin et fixer un objectif de 178 000 km d\u2019ici 2030.<\/p>\n<p>Mais plus grave encore, il y a un grand risque que la Loi soit enti\u00e8rement rejet\u00e9e, car plusieurs partis sont all\u00e9s jusqu&rsquo;\u00e0 appeler \u00e0 la rejeter compl\u00e8tement en mai dernier.\u00a0 Le vote de la commission ENVI du jeudi 15 juin doit \u00eatre \u00e0 la hauteur des enjeux.<\/p>\n<p>Envoyez un message simple et rapide aux d\u00e9cideurs pour qu&rsquo;ils soient ambitieux \u00a0: <a href=\"https:\/\/www.restorenature.eu\/en\/take-action\">https:\/\/www.restorenature.eu\/en\/take-action<\/a> #RestoreNature<\/p>\n<p>&nbsp;<\/p>\n<p>La proposition de loi sur la restauration de la nature pr\u00e9voit de restaurer des milliers de kilom\u00e8tres de rivi\u00e8res. Mobilisons nous.<\/p>\n<p>Plus d&rsquo;informations sur la <a href=\"https:\/\/www.ern.org\/fragmentation\/\">fragmentation des rivi\u00e8res<\/a><\/p>\n<p>Plus d&rsquo;information sur la <a href=\"https:\/\/www.restorenature.eu\/en\/what-is-the-nature-restoration-law\">Loi de restauration de la Nature<\/a> (anglais)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Loi sur la restauration de la Nature qui sera prochainement vot\u00e9e par les parlementaires europ\u00e9ens, fixe l&rsquo;objectif de restaurer au moins 25 000 km de cours d&rsquo;eau \u00e0 \u00e9coulement libre d&rsquo;ici \u00e0 2030 (article 7) afin d&rsquo;am\u00e9liorer la connectivit\u00e9 naturelle longitudinale et lat\u00e9rale des cours d&rsquo;eau. Ces objectifs compl\u00e8tent les obligations de la directive-cadre [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":18268,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,17,19,21,25,30,33,35,36,39,41,43],"tags":[],"class_list":["post-23895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-accueil-fr","category-dam-watch-fr","category-effacer","category-living-rivers-europe","category-menaces","category-open-rivers","category-poutes-fr","category-proteger","category-restaurer","category-salmoncomeback-fr","category-selune-fr","category-vichy"],"_links":{"self":[{"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/posts\/23895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/comments?post=23895"}],"version-history":[{"count":0,"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/posts\/23895\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/media\/18268"}],"wp:attachment":[{"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/media?parent=23895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/categories?post=23895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/tags?post=23895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}