{"id":15432,"date":"2021-09-20T12:25:03","date_gmt":"2021-09-20T10:25:03","guid":{"rendered":"https:\/\/www.ern.org\/?p=15432"},"modified":"2026-04-16T14:25:28","modified_gmt":"2026-04-16T12:25:28","slug":"saumon-de-loire-le-coup-de-grace-a-vichy","status":"publish","type":"post","link":"https:\/\/www.ern.org\/fr\/saumon-de-loire-le-coup-de-grace-a-vichy\/","title":{"rendered":"Saumon de Loire : Le coup de gr\u00e2ce \u00e0 Vichy ?"},"content":{"rendered":"<p style=\"text-align: center;\">Alors que des efforts consid\u00e9rables ont \u00e9t\u00e9 faits par l\u2019Etat, les collectivit\u00e9s territoriales, les associations et les citoyens pour sauvegarder l\u2019esp\u00e8ce, <b>le pr\u00e9fet de l\u2019Allier vient d\u2019autoriser la construction d\u2019une centrale hydraulique sur le barrage de Vichy<\/b>, condamnant d\u00e9finitivement les possibilit\u00e9s de reconqu\u00eate de l\u2019Allier par le Saumon et mena\u00e7ant tr\u00e8s directement sa survie.<br \/>\n<b>Il faut stopper ce projet aussi irresponsable que funeste.<\/b><br \/>\nUn collectif de 10 associations tant nationales que locales, dont SOS Loire Vivante, a sign\u00e9 un recours gracieux adress\u00e9 au pr\u00e9fet de l\u2019Allier. Elles envisagent un contentieux, tant national qu\u2019europ\u00e9en pour arr\u00eater ce projet d\u00e9l\u00e9t\u00e8re et le remplacer par une solution \u00e9cologiquement responsable.<\/p>\n<p style=\"text-align: center;\"><i><\/i><b> <\/b><a href=\"https:\/\/www.rivernet.org\/loire\/soslv\/compresse\/20210920_cp_vichy_vf.pdf\"><i>&gt;&gt; Lire le communiqu\u00e9 de presse des associations<\/i><\/a><b><br \/>\n<\/b><em>&gt;&gt; <\/em><a href=\"https:\/\/www.rivernet.org\/loire\/soslv\/pdfetdocs\/20210716recours_gracieux_arrete1795-2021.pdf\"><em>Voir le recours gracieux<\/em><\/a><br \/>\n<a href=\"https:\/\/www.ern.org\/fr\/vichy-non-au-projet-de-centrale-hydro\/\">&gt;&gt; Plus d&rsquo;infos sur notre page Vichy<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alors que des efforts consid\u00e9rables ont \u00e9t\u00e9 faits par l\u2019Etat, les collectivit\u00e9s territoriales, les associations et les citoyens pour sauvegarder l\u2019esp\u00e8ce, le pr\u00e9fet de l\u2019Allier vient d\u2019autoriser la construction d\u2019une centrale hydraulique sur le barrage de Vichy, condamnant d\u00e9finitivement les possibilit\u00e9s de reconqu\u00eate de l\u2019Allier par le Saumon et mena\u00e7ant tr\u00e8s directement sa survie. Il [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":14135,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,17,19,25,39,43],"tags":[],"class_list":["post-15432","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-accueil-fr","category-dam-watch-fr","category-effacer","category-menaces","category-salmoncomeback-fr","category-vichy"],"_links":{"self":[{"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/posts\/15432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/comments?post=15432"}],"version-history":[{"count":0,"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/posts\/15432\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/media\/14135"}],"wp:attachment":[{"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/media?parent=15432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/categories?post=15432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ern.org\/fr\/wp-json\/wp\/v2\/tags?post=15432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}